{"id":226515,"date":"2026-04-20T18:01:26","date_gmt":"2026-04-20T18:01:26","guid":{"rendered":""},"modified":"2026-04-20T18:01:26","modified_gmt":"2026-04-20T18:01:26","slug":"bylina","status":"publish","type":"game","link":"https:\/\/cloudgames.gg\/es\/g\/bylina\/","title":{"rendered":"Bylina"},"content":{"rendered":"","protected":false},"featured_media":226511,"template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false},"categories":[84,185,137,388,257,254,390,105,195,145,389,149],"tags":[],"class_list":["post-226515","game","type-game","status-publish","has-post-thumbnail","hentry","category-juegos-en-la-nube","category-juegos-de-airgpu","category-juegos-de-geforce-now","category-juegos-de-shadow","category-mejores-juegos-de-airgpu","category-mejores-juegos-de-geforce-now","category-mejores-juegos-de-shadow","category-mejores-juegos-en-la-nube","category-nuevos-juegos-de-airgpu","category-nuevos-juegos-de-geforce-now","category-nuevos-juegos-de-shadow","category-nuevos-juegos-en-la-nube"],"acf":[],"taxonomy_info":{"category":[{"value":84,"label":"Juegos en la nube"},{"value":185,"label":"Juegos de airgpu"},{"value":137,"label":"Juegos de GeForce Now"},{"value":388,"label":"Juegos de Shadow"},{"value":257,"label":"Mejores juegos de airgpu"},{"value":254,"label":"Mejores juegos de GeForce Now"},{"value":390,"label":"Mejores juegos de Shadow"},{"value":105,"label":"Mejores juegos en la nube"},{"value":195,"label":"Nuevos juegos de airgpu"},{"value":145,"label":"Nuevos juegos de GeForce Now"},{"value":389,"label":"Nuevos juegos de Shadow"},{"value":149,"label":"Nuevos juegos en la nube"}]},"featured_image_src_large":["https:\/\/cloudgames.gg\/wp-content\/uploads\/bylina-portrait-768x1024.jpg",768,1024,true],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/cloudgames.gg\/es\/wp-json\/wp\/v2\/game\/226515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cloudgames.gg\/es\/wp-json\/wp\/v2\/game"}],"about":[{"href":"https:\/\/cloudgames.gg\/es\/wp-json\/wp\/v2\/types\/game"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cloudgames.gg\/es\/wp-json\/wp\/v2\/media\/226511"}],"wp:attachment":[{"href":"https:\/\/cloudgames.gg\/es\/wp-json\/wp\/v2\/media?parent=226515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cloudgames.gg\/es\/wp-json\/wp\/v2\/categories?post=226515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cloudgames.gg\/es\/wp-json\/wp\/v2\/tags?post=226515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}