{"id":161079,"date":"2024-05-16T18:28:12","date_gmt":"2024-05-16T18:28:12","guid":{"rendered":""},"modified":"2024-05-16T18:28:12","modified_gmt":"2024-05-16T18:28:12","slug":"sas-zombie-assault-4","status":"publish","type":"game","link":"https:\/\/cloudgames.gg\/it\/g\/sas-zombie-assault-4\/","title":{"rendered":"SAS: Zombie Assault 4"},"content":{"rendered":"","protected":false},"featured_media":161073,"template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false},"categories":[82,183,188,131,135,139,380,383,264,103,261,381,193,147,143,382],"tags":[213],"class_list":["post-161079","game","type-game","status-publish","has-post-thumbnail","hentry","category-giochi-cloud","category-giochi-airgpu","category-giochi-airgpu-gratuiti","category-giochi-cloud-gratuiti","category-giochi-geforce-now","category-giochi-geforce-now-gratuiti","category-giochi-shadow","category-giochi-shadow-gratuiti","category-migliori-giochi-airgpu","category-migliori-giochi-cloud","category-migliori-giochi-geforce-now","category-migliori-giochi-shadow","category-nuovi-giochi-airgpu","category-nuovi-giochi-cloud","category-nuovi-giochi-geforce-now","category-nuovi-giochi-shadow","tag-free"],"acf":[],"taxonomy_info":{"category":[{"value":82,"label":"Giochi Cloud"},{"value":183,"label":"Giochi airgpu"},{"value":188,"label":"Giochi airgpu gratuiti"},{"value":131,"label":"Giochi cloud gratuiti"},{"value":135,"label":"Giochi GeForce Now"},{"value":139,"label":"Giochi GeForce Now gratuiti"},{"value":380,"label":"Giochi Shadow"},{"value":383,"label":"Giochi Shadow gratuiti"},{"value":264,"label":"Migliori giochi airgpu"},{"value":103,"label":"Migliori giochi cloud"},{"value":261,"label":"Migliori giochi GeForce Now"},{"value":381,"label":"Migliori giochi Shadow"},{"value":193,"label":"Nuovi giochi airgpu"},{"value":147,"label":"Nuovi giochi cloud"},{"value":143,"label":"Nuovi giochi GeForce Now"},{"value":382,"label":"Nuovi giochi Shadow"}],"post_tag":[{"value":213,"label":"Free"}]},"featured_image_src_large":["https:\/\/cloudgames.gg\/wp-content\/uploads\/sas-zombie-assault-4-portrait-768x1024.jpg",768,1024,true],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/cloudgames.gg\/it\/wp-json\/wp\/v2\/game\/161079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cloudgames.gg\/it\/wp-json\/wp\/v2\/game"}],"about":[{"href":"https:\/\/cloudgames.gg\/it\/wp-json\/wp\/v2\/types\/game"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cloudgames.gg\/it\/wp-json\/wp\/v2\/media\/161073"}],"wp:attachment":[{"href":"https:\/\/cloudgames.gg\/it\/wp-json\/wp\/v2\/media?parent=161079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cloudgames.gg\/it\/wp-json\/wp\/v2\/categories?post=161079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cloudgames.gg\/it\/wp-json\/wp\/v2\/tags?post=161079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}