{"id":33001,"date":"2023-11-22T00:21:50","date_gmt":"2023-11-22T00:21:50","guid":{"rendered":"wandersong::it"},"modified":"2023-11-22T00:21:50","modified_gmt":"2023-11-22T00:21:50","slug":"wandersong","status":"publish","type":"game","link":"https:\/\/cloudgames.gg\/it\/g\/wandersong\/","title":{"rendered":"Wandersong"},"content":{"rendered":"","protected":false},"featured_media":90953,"template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false},"categories":[82,183,380,168,173,264,103,381,263,193,147,382,178],"tags":[],"class_list":["post-33001","game","type-game","status-publish","has-post-thumbnail","hentry","category-giochi-cloud","category-giochi-airgpu","category-giochi-shadow","category-giochi-xbox-cloud","category-giochi-xbox-cloud-gratuiti","category-migliori-giochi-airgpu","category-migliori-giochi-cloud","category-migliori-giochi-shadow","category-migliori-giochi-xbox-cloud","category-nuovi-giochi-airgpu","category-nuovi-giochi-cloud","category-nuovi-giochi-shadow","category-nuovi-giochi-xbox-cloud"],"acf":[],"taxonomy_info":{"category":[{"value":82,"label":"Giochi Cloud"},{"value":183,"label":"Giochi airgpu"},{"value":380,"label":"Giochi Shadow"},{"value":168,"label":"Giochi Xbox cloud"},{"value":173,"label":"Giochi Xbox cloud gratuiti"},{"value":264,"label":"Migliori giochi airgpu"},{"value":103,"label":"Migliori giochi cloud"},{"value":381,"label":"Migliori giochi Shadow"},{"value":263,"label":"Migliori giochi Xbox cloud"},{"value":193,"label":"Nuovi giochi airgpu"},{"value":147,"label":"Nuovi giochi cloud"},{"value":382,"label":"Nuovi giochi Shadow"},{"value":178,"label":"Nuovi giochi Xbox cloud"}]},"featured_image_src_large":["https:\/\/cloudgames.gg\/wp-content\/uploads\/wandersong-portrait-768x1024.jpg",768,1024,true],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/cloudgames.gg\/it\/wp-json\/wp\/v2\/game\/33001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cloudgames.gg\/it\/wp-json\/wp\/v2\/game"}],"about":[{"href":"https:\/\/cloudgames.gg\/it\/wp-json\/wp\/v2\/types\/game"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cloudgames.gg\/it\/wp-json\/wp\/v2\/media\/90953"}],"wp:attachment":[{"href":"https:\/\/cloudgames.gg\/it\/wp-json\/wp\/v2\/media?parent=33001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cloudgames.gg\/it\/wp-json\/wp\/v2\/categories?post=33001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cloudgames.gg\/it\/wp-json\/wp\/v2\/tags?post=33001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}