{"id":55719,"date":"2023-11-22T05:45:47","date_gmt":"2023-11-22T05:45:47","guid":{"rendered":"tomb-raider-ii::it"},"modified":"2023-11-22T05:45:47","modified_gmt":"2023-11-22T05:45:47","slug":"tomb-raider-ii","status":"publish","type":"game","link":"https:\/\/cloudgames.gg\/it\/g\/tomb-raider-ii\/","title":{"rendered":"Tomb Raider II"},"content":{"rendered":"","protected":false},"featured_media":104576,"template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false},"categories":[82,183,119,135,380,264,260,103,261,381,193,127,147,143,382],"tags":[],"class_list":["post-55719","game","type-game","status-publish","has-post-thumbnail","hentry","category-giochi-cloud","category-giochi-airgpu","category-giochi-boosteroid","category-giochi-geforce-now","category-giochi-shadow","category-migliori-giochi-airgpu","category-migliori-giochi-boosteroid","category-migliori-giochi-cloud","category-migliori-giochi-geforce-now","category-migliori-giochi-shadow","category-nuovi-giochi-airgpu","category-nuovi-giochi-boosteroid","category-nuovi-giochi-cloud","category-nuovi-giochi-geforce-now","category-nuovi-giochi-shadow"],"acf":[],"taxonomy_info":{"category":[{"value":82,"label":"Giochi Cloud"},{"value":183,"label":"Giochi airgpu"},{"value":119,"label":"Giochi Boosteroid"},{"value":135,"label":"Giochi GeForce Now"},{"value":380,"label":"Giochi Shadow"},{"value":264,"label":"Migliori giochi airgpu"},{"value":260,"label":"Migliori giochi Boosteroid"},{"value":103,"label":"Migliori giochi cloud"},{"value":261,"label":"Migliori giochi GeForce Now"},{"value":381,"label":"Migliori giochi Shadow"},{"value":193,"label":"Nuovi giochi airgpu"},{"value":127,"label":"Nuovi giochi Boosteroid"},{"value":147,"label":"Nuovi giochi cloud"},{"value":143,"label":"Nuovi giochi GeForce Now"},{"value":382,"label":"Nuovi giochi Shadow"}]},"featured_image_src_large":["https:\/\/cloudgames.gg\/wp-content\/uploads\/tomb-raider-ii-portrait-768x1024.jpg",768,1024,true],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/cloudgames.gg\/it\/wp-json\/wp\/v2\/game\/55719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cloudgames.gg\/it\/wp-json\/wp\/v2\/game"}],"about":[{"href":"https:\/\/cloudgames.gg\/it\/wp-json\/wp\/v2\/types\/game"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cloudgames.gg\/it\/wp-json\/wp\/v2\/media\/104576"}],"wp:attachment":[{"href":"https:\/\/cloudgames.gg\/it\/wp-json\/wp\/v2\/media?parent=55719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cloudgames.gg\/it\/wp-json\/wp\/v2\/categories?post=55719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cloudgames.gg\/it\/wp-json\/wp\/v2\/tags?post=55719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}